{"id":18447,"date":"2018-10-26T23:02:08","date_gmt":"2018-10-26T15:02:08","guid":{"rendered":"\/blog\/?p=18447"},"modified":"2018-11-02T09:41:07","modified_gmt":"2018-11-02T01:41:07","slug":"last-minute-electronic-trick-treat-for-halloween","status":"publish","type":"post","link":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/","title":{"rendered":"Halloween Sale: Trick or Treat? You\u2019ll Never Know!"},"content":{"rendered":"<p>Halloween is just around the corner. It is a festival to embrace ghosts, witches and door-to-door masquerade in search for candies after shouting out \u201cTrick or Treat\u201d!<\/p>\n<p class=\"p1\">It\u2019s always a lot of fun to empower your holiday decor or masquerade with some quirky tech. Still looking for a last-minute idea for your Halloween projects?<\/p>\n<p>Here comes\u00a0a step-by-step recipe for you to create a frightening pumpkin candy machine! It\u2019s in a shape of pumpkin lantern, with\u00a0Seeeduino and PIR Motion Sensor\u00a0attached. When someone\u00a0gets\u00a0close, it will trigger a scary music to frighten them. And it will generously offer candies after its little trick!!! Check out the\u00a0<span style=\"color: #106fe3;\"><a style=\"color: #106fe3;\" href=\"https:\/\/project.seeedstudio.com\/SeeedStudio\/scary-pumpkin-candy-machine-for-halloween-a10011\"><u>step-by-step tutorial<\/u><\/a><\/span>\u00a0on our\u00a0<span style=\"color: #106fe3;\"><a style=\"color: #106fe3;\" href=\"https:\/\/project.seeedstudio.com\/\"><u>Project Hub<\/u><\/a><\/span>. Trick or treat? You\u2019ll\u00a0never know!<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-18447-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/blog.seeedstudio.com\/wp-content\/uploads\/2018\/10\/Scary-Pumpkin-Candy-Machine-for-Halloween.mp4?_=1\" \/><a href=\"https:\/\/blog.seeedstudio.com\/wp-content\/uploads\/2018\/10\/Scary-Pumpkin-Candy-Machine-for-Halloween.mp4\">https:\/\/blog.seeedstudio.com\/wp-content\/uploads\/2018\/10\/Scary-Pumpkin-Candy-Machine-for-Halloween.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>Of course, we\u2019ve prepared some special\u00a0treat for this lovely holiday! Enjoy $15 off for every Bazaar Order over $100. You could use the coupon code to enjoy the treat from Seeed during\u00a0October 29th and\u00a0November 2nd, 2018.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-18451 size-full\" src=\"https:\/\/blog.seeedstudio.com\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181026194856.png\" alt=\"\" width=\"1031\" height=\"236\" srcset=\"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181026194856.png 1031w, https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181026194856-300x69.png 300w, https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181026194856-768x176.png 768w, https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181026194856-1030x236.png 1030w\" sizes=\"(max-width: 1031px) 100vw, 1031px\" \/><\/p>\n<p>Coupon\u00a0Code:\u00a0<span style=\"color: #00ccff;\"><strong>TREAT15<\/strong><\/span><br \/>\nOctober 29th to November 2nd (GMT+8)<br \/>\nThe coupon will be expired on November 3rd (GMT+8).<\/p>\n<p>Tips for the Treat:<\/p>\n<ul>\n<li>$100 minimum spend (excluding shipping fee)<\/li>\n<li>Seeed reserves the rights to the final interpretation of rules. And if any question or inputs, please contact us at <a href=\"mailto:order@seeed.cc\"><span style=\"color: #106fe3;\">order@seeed.cc<\/span><\/a><\/li>\n<li>The coupon code is only for retail orders on Seeed Bazaar, not applicable for Fusion services, bundle sales orders or wholesale orders. .(We love you too!)<\/li>\n<\/ul>\n<p>Enjoy a\u00a0spooky Halloween\u00a0with this little treat from Seeed!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Halloween is just around the corner. It is a festival to embrace ghosts, witches and<\/p>\n","protected":false},"author":150,"featured_media":18476,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[672],"class_list":["post-18447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-respeaker"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio\" \/>\n<meta property=\"og:description\" content=\"Halloween is just around the corner. It is a festival to embrace ghosts, witches and\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/\" \/>\n<meta property=\"og:site_name\" content=\"Latest News from Seeed Studio\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-26T15:02:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-02T01:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png\" \/>\n\t<meta property=\"og:image:width\" content=\"741\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/\",\"url\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/\",\"name\":\"Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio\",\"isPartOf\":{\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png\",\"datePublished\":\"2018-10-26T15:02:08+00:00\",\"dateModified\":\"2018-11-02T01:41:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/e41d9353184fc0b7650686004ed5eb50\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage\",\"url\":\"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png\",\"contentUrl\":\"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png\",\"width\":741,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.seeedstudio.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halloween Sale: Trick or Treat? You\u2019ll Never Know!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/#website\",\"url\":\"https:\/\/www.seeedstudio.com\/blog\/\",\"name\":\"Latest News from Seeed Studio\",\"description\":\"Emerging IoT, AI and Autonomous Applications on the Edge\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.seeedstudio.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/e41d9353184fc0b7650686004ed5eb50\",\"name\":\"Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ec5316369f1dd9f2b092db2c29821758?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ec5316369f1dd9f2b092db2c29821758?s=96&r=g\",\"caption\":\"Dana\"},\"url\":\"https:\/\/www.seeedstudio.com\/blog\/author\/dana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/","og_locale":"en_US","og_type":"article","og_title":"Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio","og_description":"Halloween is just around the corner. It is a festival to embrace ghosts, witches and","og_url":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/","og_site_name":"Latest News from Seeed Studio","article_published_time":"2018-10-26T15:02:08+00:00","article_modified_time":"2018-11-02T01:41:07+00:00","og_image":[{"width":741,"height":556,"url":"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png","type":"image\/png"}],"author":"Dana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dana","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/","url":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/","name":"Halloween Sale: Trick or Treat? You\u2019ll Never Know! - Latest News from Seeed Studio","isPartOf":{"@id":"https:\/\/www.seeedstudio.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage"},"image":{"@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage"},"thumbnailUrl":"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png","datePublished":"2018-10-26T15:02:08+00:00","dateModified":"2018-11-02T01:41:07+00:00","author":{"@id":"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/e41d9353184fc0b7650686004ed5eb50"},"breadcrumb":{"@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#primaryimage","url":"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png","contentUrl":"https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png","width":741,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/www.seeedstudio.com\/blog\/2018\/10\/26\/last-minute-electronic-trick-treat-for-halloween\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.seeedstudio.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Halloween Sale: Trick or Treat? You\u2019ll Never Know!"}]},{"@type":"WebSite","@id":"https:\/\/www.seeedstudio.com\/blog\/#website","url":"https:\/\/www.seeedstudio.com\/blog\/","name":"Latest News from Seeed Studio","description":"Emerging IoT, AI and Autonomous Applications on the Edge","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seeedstudio.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/e41d9353184fc0b7650686004ed5eb50","name":"Dana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.seeedstudio.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ec5316369f1dd9f2b092db2c29821758?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec5316369f1dd9f2b092db2c29821758?s=96&r=g","caption":"Dana"},"url":"https:\/\/www.seeedstudio.com\/blog\/author\/dana\/"}]}},"modified_by":"Lily","views":17335,"featured_image_urls":{"full":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"thumbnail":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802-80x80.png",80,80,true],"medium":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802-300x225.png",300,225,true],"medium_large":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",640,480,false],"large":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",640,480,false],"1536x1536":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"2048x2048":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"visody_icon":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",32,24,false],"magazine-7-slider-full":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"magazine-7-slider-center":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"magazine-7-featured":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",741,556,false],"magazine-7-medium":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",506,380,false],"magazine-7-medium-square":["https:\/\/www.seeedstudio.com\/blog\/wp-content\/uploads\/2018\/10\/\u4e91\u4e4b\u5bb6\u56fe\u724720181029102802.png",600,450,false]},"author_info":{"display_name":"Dana","author_link":"https:\/\/www.seeedstudio.com\/blog\/author\/dana\/"},"category_info":"<a href=\"https:\/\/www.seeedstudio.com\/blog\/category\/news\/\" rel=\"category tag\">News<\/a>","tag_info":"News","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/posts\/18447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/comments?post=18447"}],"version-history":[{"count":26,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/posts\/18447\/revisions"}],"predecessor-version":[{"id":18501,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/posts\/18447\/revisions\/18501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/media\/18476"}],"wp:attachment":[{"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/media?parent=18447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/categories?post=18447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seeedstudio.com\/blog\/wp-json\/wp\/v2\/tags?post=18447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}